{"id":1210,"date":"2022-09-17T18:32:58","date_gmt":"2022-09-17T18:32:58","guid":{"rendered":"https:\/\/www.accs.pt\/accs\/?p=1210"},"modified":"2022-09-17T18:33:00","modified_gmt":"2022-09-17T18:33:00","slug":"rampa-sc-santacruzense-2022-encerramento-de-estradas-para-os-reconhecimentos-da-super-especial","status":"publish","type":"post","link":"http:\/\/www.accs.pt\/accs\/2022\/09\/17\/rampa-sc-santacruzense-2022-encerramento-de-estradas-para-os-reconhecimentos-da-super-especial\/","title":{"rendered":"Rampa SC Santacruzense 2022 &#8211; Encerramento de Estradas para os reconhecimentos da Super Especial"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"987\" height=\"567\" src=\"http:\/\/www.accs.pt\/accs\/wp-content\/uploads\/2022\/09\/logo_para_numeros_porta.jpg\" alt=\"\" class=\"wp-image-1185\" srcset=\"http:\/\/www.accs.pt\/accs\/wp-content\/uploads\/2022\/09\/logo_para_numeros_porta.jpg 987w, http:\/\/www.accs.pt\/accs\/wp-content\/uploads\/2022\/09\/logo_para_numeros_porta-300x172.jpg 300w, http:\/\/www.accs.pt\/accs\/wp-content\/uploads\/2022\/09\/logo_para_numeros_porta-768x441.jpg 768w\" sizes=\"auto, (max-width: 987px) 100vw, 987px\" \/><\/figure>\n\n\n\n<p>Na segunda feira, dia 19 de setembro, teremos os reconhecimentos da super especial, Como tal existir\u00e3o condicionamentos de tr\u00e2nsito na Freguesia de Santo Ant\u00f3nio da Serra. <\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/www.accs.pt\/accs\/wp-content\/uploads\/2022\/09\/Edital_Rampa-do-SC-Santacruzense_19_09_22.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Incorpora\u00e7\u00e3o de Incorpora\u00e7\u00e3o de Edital_Rampa-do-SC-Santacruzense_19_09_22..\"><\/object><a id=\"wp-block-file--media-55a768b0-b565-4297-9ea4-59e0c51197b2\" href=\"https:\/\/www.accs.pt\/accs\/wp-content\/uploads\/2022\/09\/Edital_Rampa-do-SC-Santacruzense_19_09_22.pdf\">Edital_Rampa-do-SC-Santacruzense_19_09_22<\/a><a href=\"https:\/\/www.accs.pt\/accs\/wp-content\/uploads\/2022\/09\/Edital_Rampa-do-SC-Santacruzense_19_09_22.pdf\" class=\"wp-block-file__button\" download aria-describedby=\"wp-block-file--media-55a768b0-b565-4297-9ea4-59e0c51197b2\">Descarregar<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<div class=\"slide-text-bg2\">\n<h3>Na segunda feira, dia 19 de setembro, teremos os reconhecimentos da super especial, Como tal existir\u00e3o condicionamentos de tr\u00e2nsito na<\/h3>\n<\/div>\n<div class=\"flex-btn-div\"><a href=\"http:\/\/www.accs.pt\/accs\/2022\/09\/17\/rampa-sc-santacruzense-2022-encerramento-de-estradas-para-os-reconhecimentos-da-super-especial\/\" class=\"btn1 flex-btn\">Ler mais<\/a><\/div>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1210","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"http:\/\/www.accs.pt\/accs\/wp-json\/wp\/v2\/posts\/1210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.accs.pt\/accs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.accs.pt\/accs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.accs.pt\/accs\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.accs.pt\/accs\/wp-json\/wp\/v2\/comments?post=1210"}],"version-history":[{"count":1,"href":"http:\/\/www.accs.pt\/accs\/wp-json\/wp\/v2\/posts\/1210\/revisions"}],"predecessor-version":[{"id":1212,"href":"http:\/\/www.accs.pt\/accs\/wp-json\/wp\/v2\/posts\/1210\/revisions\/1212"}],"wp:attachment":[{"href":"http:\/\/www.accs.pt\/accs\/wp-json\/wp\/v2\/media?parent=1210"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.accs.pt\/accs\/wp-json\/wp\/v2\/categories?post=1210"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.accs.pt\/accs\/wp-json\/wp\/v2\/tags?post=1210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}